{"id":30156,"date":"2019-08-16T09:15:26","date_gmt":"2019-08-16T07:15:26","guid":{"rendered":"https:\/\/sha.de\/experiencia"},"modified":"2024-08-28T15:03:43","modified_gmt":"2024-08-28T13:03:43","slug":"experiencia","status":"publish","type":"page","link":"https:\/\/sha.de\/es\/experiencia","title":{"rendered":"Experiencia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":18,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-30156","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experiencia - SHA Scheffler Helbich Architekten GmbH<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiencia - SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sha.de\/es\/experiencia\" \/>\n<meta property=\"og:site_name\" content=\"SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T13:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/experiencia\",\"url\":\"https:\\\/\\\/sha.de\\\/es\\\/experiencia\",\"name\":\"Experiencia - SHA Scheffler Helbich Architekten GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es#website\"},\"datePublished\":\"2019-08-16T07:15:26+00:00\",\"dateModified\":\"2024-08-28T13:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/experiencia#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sha.de\\\/es\\\/experiencia\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/experiencia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sha.de\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sha.de\\\/es#website\",\"url\":\"https:\\\/\\\/sha.de\\\/es\",\"name\":\"SHA Scheffler Helbich Architekten GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sha.de\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiencia - SHA Scheffler Helbich Architekten GmbH","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Experiencia - SHA Scheffler Helbich Architekten GmbH","og_url":"https:\/\/sha.de\/es\/experiencia","og_site_name":"SHA Scheffler Helbich Architekten GmbH","article_modified_time":"2024-08-28T13:03:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sha.de\/es\/experiencia","url":"https:\/\/sha.de\/es\/experiencia","name":"Experiencia - SHA Scheffler Helbich Architekten GmbH","isPartOf":{"@id":"https:\/\/sha.de\/es#website"},"datePublished":"2019-08-16T07:15:26+00:00","dateModified":"2024-08-28T13:03:43+00:00","breadcrumb":{"@id":"https:\/\/sha.de\/es\/experiencia#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sha.de\/es\/experiencia"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sha.de\/es\/experiencia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sha.de\/es"},{"@type":"ListItem","position":2,"name":"Experiencia"}]},{"@type":"WebSite","@id":"https:\/\/sha.de\/es#website","url":"https:\/\/sha.de\/es","name":"SHA Scheffler Helbich Architekten GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sha.de\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/pages\/30156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/comments?post=30156"}],"version-history":[{"count":1,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/pages\/30156\/revisions"}],"predecessor-version":[{"id":39150,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/pages\/30156\/revisions\/39150"}],"wp:attachment":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/media?parent=30156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}