{"id":34006,"date":"2020-09-24T13:47:35","date_gmt":"2020-09-24T11:47:35","guid":{"rendered":"https:\/\/sha.de\/aktuelles\/phoenixwerk-nueva-obra-en-dortmund"},"modified":"2024-09-23T16:54:53","modified_gmt":"2024-09-23T14:54:53","slug":"phoenixwerk-nueva-obra-en-dortmund","status":"publish","type":"post","link":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund","title":{"rendered":"PhoenixWERK: nueva obra en Dortmund"},"content":{"rendered":"<div id='av_section_1' class='avia-section main_color pt-default pb-default avia-no-border-styling avia-bg-style-scroll  avia-builder-el-0  avia-builder-el-no-sibling   container_wrap fullsize' style=' '  ><div class='container' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-34006'><div class='entry-content-wrapper clearfix'>\n\n\t\t\t<div id=\"av-k1hoeuzj\" class=\"headline-column flex_column av_one_full flex_column_div first \">\n\t\t\t\t<div class=\"headline-wrap is-outside align-left sub-bottom\">\n\t\t\t\t\t<h1 class=\"headline-content headline-primary\">PhoenixWERK: nueva obra en Dortmund<\/h1>\n\t\t\t\t\t<h3 class=\"headline-content headline-secondary\">&quot;La ubicaci\u00f3n con car\u00e1cter nos inspir\u00f3 desde el principio&quot;<\/h3>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default      avia-builder-el-2  el_after_pixel_sc_headline  el_before_av_one_third  \"><section  class='av_textblock_section av-kfgpxslt-ea45c4f6a96ab89e301f07421d1279df '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>En el antiguo emplazamiento de <a href=\"https:\/\/www.wirtschaftsfoerderung-dortmund.de\/investition\/phoenix-west\" target=\"_blank\" rel=\"noopener nofollow\">la<\/a> acer\u00eda <a href=\"https:\/\/www.wirtschaftsfoerderung-dortmund.de\/investition\/phoenix-west\" target=\"_blank\" rel=\"noopener nofollow\">PHOENIX<\/a> West, se han terminado los dos primeros componentes de un complejo de oficinas de futuro en una superficie de unos 9.000 m\u00b2. Con su puntiaguda y clara orientaci\u00f3n hacia el hist\u00f3rico alto horno y la Sala de M\u00fasica Warsteiner, es una reminiscencia de la cultura industrial de la cuenca del Ruhr: el <a href=\"https:\/\/sha.de\/es\/proyectos\/oficina-y-administracion\/innovador-espacio-de-trabajo-en-phoenix-west-en-dortmund-horde\">PhoenixWERK<\/a>, proyectado, realizado y ahora ocupado por SHA Scheffler Helbich Architekten. Pertenece, pues, a la \u00abgeneraci\u00f3n fundadora\u00bb de varias empresas del a\u00fan joven centro de innovaci\u00f3n del sur de Dortmund.<\/p>\n<p>\u00abEstamos encantados y orgullosos de poder trabajar cada d\u00eda para nuestros clientes desde aqu\u00ed\u00bb, afirma <a href=\"https:\/\/sha.de\/es\/nuestra-oficina\/gestion\">Christoph Helbich<\/a>, socio gerente de SHA. Aqu\u00ed, en PHOENIX West, en el barrio de H\u00f6rde, se han reunido las dos sedes anteriores del estudio de arquitectura en Dortmund. \u00abLa propiedad y la ubicaci\u00f3n con car\u00e1cter nos convencieron desde el principio\u00bb, afirma entusiasmado Christoph Helbich. SHA, junto con Remira, que construy\u00f3 la segunda parte del edificio, tom\u00f3 la iniciativa del proyecto buscando una nueva sede para la empresa. Es el entorno perfecto para la tradicional empresa familiar, que ha crecido enormemente en los \u00faltimos a\u00f1os gracias a su especializaci\u00f3n.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding        avia-builder-el-4  el_after_av_one_third  el_before_av_one_third  \"><section  class='av_textblock_section av-kaqj9hph-706c318c8f487264c95b3db12998d912 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>A partir de PHOENIX West, SHA ampliar\u00e1 a\u00fan m\u00e1s sus actividades en los pr\u00f3ximos a\u00f1os y apoyar\u00e1 a sus clientes de toda Alemania como socio fuerte y \u00abcuidador de la A a la Z\u00bb en todas las fases del proyecto.<\/p>\n<p>A largo plazo, se construir\u00e1n otros tres tramos de edificios en el solar -incluido un aparcamiento de varias plantas a finales de a\u00f1o- que completar\u00e1n el barrio en funci\u00f3n de la demanda. Los dos componentes restantes a\u00fan pueden ser adquiridos por los inversores. \u00abTodo se basa en una idea del campus\u00bb, explica Christoph Helbich. El aparcamiento de varias plantas garantiza el acceso sin coches al recinto y, junto con el verde patio interior, una estancia de gran calidad para todos los inquilinos. Con su fachada de ladrillo clinker, el aparcamiento de varias plantas contin\u00faa armoniosamente el lenguaje del PhoenixWERK.<\/p>\n<p><strong>Acerca del PhoenixWERK<\/strong><\/p>\n<p>El conjunto de oficinas PhoenixWERK se integra con naturalidad en el entorno hist\u00f3rico de PHOENIX West y crea al mismo tiempo un entorno de trabajo prestigioso y \u00fanico para sus usuarios. Oficinas de alta calidad con amplias terrazas en los pisos superiores y <a href=\"https:\/\/www.das-hoesch.restaurant\/\" target=\"_blank\" rel=\"noopener nofollow\">restaurantes<\/a> en la planta baja con una extensa zona al aire libre ya complementan lo que faltaba<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding        avia-builder-el-6  el_after_av_one_third  el_before_av_one_full  \"><section  class='av_textblock_section av-kdhemomz-e6892157fe883912ee1fde13a7af5956 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>El nuevo edificio crear\u00e1 un nuevo borde espacial a la Phoenixplatz y la reforzar\u00e1 as\u00ed como llamativo centro del barrio con un tel\u00f3n de fondo hist\u00f3rico.<\/p>\n<p>Enmarcada por el Warsteiner Music Hall, el Schalthaus 101 y el PhoenixWERK, la plaza se ha convertido en un animado lugar de encuentro, y no s\u00f3lo durante los actos culturales.<\/p>\n<p>Las pr\u00f3ximas fases de construcci\u00f3n proporcionar\u00e1n espacio para m\u00e1s de 250 empleados en el futuro. Los generosos frentes de ventana permiten una distribuci\u00f3n de la sala inundada de luz para las oficinas contempor\u00e1neas: Las nuevas formas de trabajar no son aqu\u00ed s\u00f3lo una palabra de moda, sino una realidad cotidiana. Ya sean oficinas individuales o de planta abierta, todo es posible en PhoenixWERK. Los retiros son tan posibles como el trabajo en equipo en las zonas comunales comunicativas. Las referencias internas a los edificios existentes circundantes son coherentes en todo el conjunto. Todas las entradas son acogedoras y sin barreras y ofrecen acceso directo al patio interior compartido a largo plazo. Los m\u00e9todos de construcci\u00f3n sostenibles y respetuosos con los recursos, la tecnolog\u00eda punta y los materiales de alta calidad son componentes clave del concepto, que puede responder a los deseos y requisitos individuales de inquilinos e inversores. Adem\u00e1s, el funcionamiento econ\u00f3mico y ecol\u00f3gico es una prioridad especialmente alta.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first       avia-builder-el-8  el_after_av_one_third  avia-builder-el-last  column-top-margin\"><div class=\"slickgallery \">\n\t<div class=\"pixel-slide-wrap\">\n\t\t<div class=\"pixel-slide\" style=\"display: block; width: 100%; float: left;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-1\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-680-2-1280x838.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-680-2-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-2\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-171-567x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-171-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-3\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-162-569x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-162-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-4\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1-1274x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-5\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-462-1274x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-462-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-6\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-444-571x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-444-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-7\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-856-1274x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-856-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-8\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-436-1274x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-436-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-9\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/PhoenixWERK_Farbe_Web-9-1275x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/PhoenixWERK_Farbe_Web-9-706x368.jpg\" alt=\"PhoenixWERK Farbe Web 9\" title=\"PhoenixWERK Farbe Web 9\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-10\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-138-1274x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-138-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-11\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-066-567x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-066-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-12\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-1143-1280x843.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-1143-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-13\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-1110-567x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-1110-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-14\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-755-570x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-755-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pixel-slide__image-wrap slide-15\">\n\t\t\t\t\t\t\t<div class=\"pixel-slide__image \"><a href=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-769-570x850.jpg\" rel=\"lightbox\"><img decoding=\"async\" src=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-769-706x368.jpg\" alt=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\" title=\"PhoenixWerk Dortmund SHA Scheffler Helbich Architekten\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En los antiguos terrenos de la acer\u00eda PHOENIX West se han terminado los dos primeros componentes de un complejo de oficinas pionero en una superficie de unos 9.000 m\u00b2: el PhoenixWERK.<\/p>\n","protected":false},"author":2,"featured_media":23624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[905,894,902],"tags":[1020,1052,1074,1096,1097,1098,1009,1019],"class_list":["post-34006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","category-dortmund-es","category-nuestro-equipo","tag-oficina","tag-dortmund-es","tag-edificio-nuevo","tag-christoph-helbich-es","tag-planta-de-phoenix","tag-edificio-administrativo","tag-sha-es","tag-edificio-de-oficinas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PhoenixWERK: nueva obra en Dortmund<\/title>\n<meta name=\"description\" content=\"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PhoenixWERK: nueva obra en Dortmund\" \/>\n<meta property=\"og:description\" content=\"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund\" \/>\n<meta property=\"og:site_name\" content=\"SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T11:47:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T14:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Judith Weitzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Judith Weitzel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund\"},\"author\":{\"name\":\"Judith Weitzel\",\"@id\":\"https:\\\/\\\/sha.de\\\/es#\\\/schema\\\/person\\\/6d5fd32d5aa7872f1f9191b7244552c9\"},\"headline\":\"PhoenixWERK: nueva obra en Dortmund\",\"datePublished\":\"2020-09-24T11:47:35+00:00\",\"dateModified\":\"2024-09-23T14:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund\"},\"wordCount\":1259,\"image\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/CE655-587-1.jpg\",\"keywords\":[\"Oficina\",\"Dortmund\",\"Edificio nuevo\",\"Christoph Helbich\",\"Planta de Phoenix\",\"Edificio administrativo\",\"SHA\",\"Edificio de oficinas\"],\"articleSection\":[\"Administraci\u00f3n\",\"Dortmund\",\"Nuestro equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund\",\"url\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund\",\"name\":\"PhoenixWERK: nueva obra en Dortmund\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/CE655-587-1.jpg\",\"datePublished\":\"2020-09-24T11:47:35+00:00\",\"dateModified\":\"2024-09-23T14:54:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es#\\\/schema\\\/person\\\/6d5fd32d5aa7872f1f9191b7244552c9\"},\"description\":\"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#primaryimage\",\"url\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/CE655-587-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/CE655-587-1.jpg\",\"width\":1800,\"height\":1201},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sha.de\\\/es\\\/news\\\/phoenixwerk-nueva-obra-en-dortmund#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sha.de\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PhoenixWERK: nueva obra en Dortmund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sha.de\\\/es#website\",\"url\":\"https:\\\/\\\/sha.de\\\/es\",\"name\":\"SHA Scheffler Helbich Architekten GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sha.de\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sha.de\\\/es#\\\/schema\\\/person\\\/6d5fd32d5aa7872f1f9191b7244552c9\",\"name\":\"Judith Weitzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g\",\"caption\":\"Judith Weitzel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PhoenixWERK: nueva obra en Dortmund","description":"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund","og_locale":"es_ES","og_type":"article","og_title":"PhoenixWERK: nueva obra en Dortmund","og_description":"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.","og_url":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund","og_site_name":"SHA Scheffler Helbich Architekten GmbH","article_published_time":"2020-09-24T11:47:35+00:00","article_modified_time":"2024-09-23T14:54:53+00:00","og_image":[{"width":1800,"height":1201,"url":"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg","type":"image\/jpeg"}],"author":"Judith Weitzel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Judith Weitzel","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#article","isPartOf":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund"},"author":{"name":"Judith Weitzel","@id":"https:\/\/sha.de\/es#\/schema\/person\/6d5fd32d5aa7872f1f9191b7244552c9"},"headline":"PhoenixWERK: nueva obra en Dortmund","datePublished":"2020-09-24T11:47:35+00:00","dateModified":"2024-09-23T14:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund"},"wordCount":1259,"image":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#primaryimage"},"thumbnailUrl":"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg","keywords":["Oficina","Dortmund","Edificio nuevo","Christoph Helbich","Planta de Phoenix","Edificio administrativo","SHA","Edificio de oficinas"],"articleSection":["Administraci\u00f3n","Dortmund","Nuestro equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund","url":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund","name":"PhoenixWERK: nueva obra en Dortmund","isPartOf":{"@id":"https:\/\/sha.de\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#primaryimage"},"image":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#primaryimage"},"thumbnailUrl":"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg","datePublished":"2020-09-24T11:47:35+00:00","dateModified":"2024-09-23T14:54:53+00:00","author":{"@id":"https:\/\/sha.de\/es#\/schema\/person\/6d5fd32d5aa7872f1f9191b7244552c9"},"description":"Se han terminado los dos primeros componentes de un complejo de oficinas pionero en el emplazamiento de una antigua acer\u00eda: el PhoenixWERK.","breadcrumb":{"@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#primaryimage","url":"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg","contentUrl":"https:\/\/sha.de\/wp-content\/uploads\/CE655-587-1.jpg","width":1800,"height":1201},{"@type":"BreadcrumbList","@id":"https:\/\/sha.de\/es\/news\/phoenixwerk-nueva-obra-en-dortmund#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sha.de\/es"},{"@type":"ListItem","position":2,"name":"PhoenixWERK: nueva obra en Dortmund"}]},{"@type":"WebSite","@id":"https:\/\/sha.de\/es#website","url":"https:\/\/sha.de\/es","name":"SHA Scheffler Helbich Architekten GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sha.de\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sha.de\/es#\/schema\/person\/6d5fd32d5aa7872f1f9191b7244552c9","name":"Judith Weitzel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7dca018fdb593c021709193ddb78dc530485d187ec667fb2a0ae6c4097c9957?s=96&d=mm&r=g","caption":"Judith Weitzel"}}]}},"_links":{"self":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/posts\/34006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/comments?post=34006"}],"version-history":[{"count":4,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/posts\/34006\/revisions"}],"predecessor-version":[{"id":47810,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/posts\/34006\/revisions\/47810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/media\/23624"}],"wp:attachment":[{"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/media?parent=34006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/categories?post=34006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sha.de\/es\/wp-json\/wp\/v2\/tags?post=34006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}