{"id":54158,"date":"2025-08-05T08:51:21","date_gmt":"2025-08-05T06:51:21","guid":{"rendered":"https:\/\/sha.de\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse"},"modified":"2025-08-12T15:56:58","modified_gmt":"2025-08-12T13:56:58","slug":"erkenning-voor-het-havengebied-suedliche-speicherstrasse","status":"publish","type":"post","link":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse","title":{"rendered":"Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe"},"content":{"rendered":"<div id='av_section_1' class='avia-section main_color pt-default pb-default avia-no-border-styling avia-bg-style-scroll  avia-builder-el-0  avia-builder-el-no-sibling   container_wrap fullsize' style=' '  ><div class='container' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-54158'><div class='entry-content-wrapper clearfix'>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first bg-default   img-left   avia-builder-el-1  el_before_av_two_third  avia-builder-el-first  \"><p>\n\t\t\t<div id=\"av-mdy69qvc\" class=\"headline-column flex_column av_one_full flex_column_div first ,,,,,,,\">\n\t\t\t\t<div class=\"headline-wrap is-outside align-left sub-bottom\">\n\t\t\t\t\t<h1 class=\"headline-content headline-primary\">Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe<\/h1>\n\t\t\t\t\t<h2 class=\"headline-content headline-secondary\">Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.<\/h2>\n\t\t\t\t<\/div>\n\t\t\t<\/div><br \/>\n<div  class='avia-image-container  av-styling-    avia-builder-el-3  el_after_pixel_sc_headline  avia-builder-el-last  avia-align-center'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img class='avia_image' src='https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-scaled-e1754373154559.jpg' alt='' title='default' height=\"1920\" width=\"2560\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/p><\/div><div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding first bg-default   img-left   avia-builder-el-4  el_after_av_one_full  el_before_av_one_third  column-top-margin\"><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mdy6flyd-3168874dc52a9d903852f0d98f704922\">\n#top .av_textblock_section.av-mdy6flyd-3168874dc52a9d903852f0d98f704922 .avia_textblock{\ncolumn-count:2;\n}\n\n@media only screen and (max-width: 479px){ \n#top .av_textblock_section.av-mdy6flyd-3168874dc52a9d903852f0d98f704922 .avia_textblock{\ncolumn-count:1;\n}\n.av_textblock_section.av-mdy6flyd-3168874dc52a9d903852f0d98f704922 .avia_textblock.av_multi_colums > p:first-child{\nmargin-top:0.85em;\n}\n}\n<\/style>\n<section  class='av_textblock_section av-mdy6flyd-3168874dc52a9d903852f0d98f704922 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_multi_colums'  itemprop=\"text\" ><h2>Een wijk tussen industrieel erfgoed en digitale toekomst<\/h2>\n<p>De transformatie van het historische havengebied staat symbool voor een nieuw type stedelijke ontwikkeling: een die het gebouwde erfgoed niet overdekt, maar productief naar de toekomst leidt. Tussen oude sporen, monumentale pakhuizen en de nieuwe havenboulevard ontstaat een wijk die creatieve economie, digitalisering en sociale integratie op een bijzondere manier met elkaar verbindt.<\/p>\n<p>In de laudatio bij de prijsuitreiking staat treffend:<br \/>\n\u201cHet havengebied in Dortmund laat op indrukwekkende en voorbeeldige wijze zien hoe een industriegebied een toekomstbestendige stadswijk wordt, die innovatie, identiteit en integratie verenigt \u2013 met een uitstraling die ver buiten Dortmund reikt.\u201d (Anja Reichert-Schick)<\/p>\n<h2>Lensing Media Port \u2013 een architectonisch signaal<\/h2>\n<p>Onze bijdrage, de Lensing Media Port, zet in deze context een markant architectonisch accent. Het staat symbool voor de nieuwe gebruikslaag, die zich zowel gevoelig als krachtig in de bestaande structuur voegt. Als plek voor werken, netwerken en communiceren brengt het de toekomst van de mediawereld naar de haven en maakt tegelijkertijd het industri\u00eble verleden nog steeds beleefbaar in materiaalkeuze en ruimtelijke structuur.<\/p>\n<p>De erkenning geldt niet alleen voor het architectonische en stedenbouwkundige ontwerp, maar ook voor het intensieve samenwerkingsproces dat het project heeft gedragen: tussen stadsbestuur, investeerders, planners, maatschappelijk middenveld en subsidieverstrekkers. Bijzonder verheugend is het grote aandeel openbare ruimtes: meer dan 50 procent van de wijk blijft voorbehouden aan de stadsgemeenschap \u2013 in de vorm van promenades, speeltuinen, verblijfsruimtes en culturele voorzieningen.<\/p>\n<p>De onderscheiding verankert het project in de landelijke waarneming: vanaf september wordt het havengebied gepresenteerd als onderdeel van een <b>landelijke reizende tentoonstelling \u201cStadt Bauen\u201d<\/b> en een publicatie die stedenbouwkundige voorbeelden in Duitsland presenteert.<\/p>\n<p>We zijn verheugd een bijdrage te hebben kunnen leveren aan de bekroonde wijkontwikkeling. Onze architectuur staat voor de geslaagde synthese van industri\u00eble substantie en digitale toekomst. Wij danken alle betrokkenen \u2013 in het bijzonder de stad Dortmund, de Stiftung Soziale Stadt, private opdrachtgevers en de burgerij voor de vertrouwensvolle samenwerking. Dit is zowel motivatie als verplichting: we kijken ernaar uit om te blijven bijdragen aan stedenbouwkundige projecten die architectuur, identiteit en maatschappelijke participatie verenigen.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default   img-left   avia-builder-el-6  el_after_av_two_third  avia-builder-el-last  column-top-margin\"><div class=\"call-to-action    has-button ci-black hover-white bg-yellow  align-left \"><div class=\"call-to-action__inner\"><div class=\"call-to-action__text\"><span class=\"call-to-action__primary\">Ontdek nu meer!<\/span><span class=\"call-to-action__secondary\">Meer informatie over de erkenning van het Dortmundse havengebied.<\/span><\/div><div class=\"call-to-action__button\"><div class=\"avia-button-wrap theme-fill avia-button-left\"><a href=\"https:\/\/www.dasl.de\/deutscher-staedtebau-preis\/preistraeger\" class=\"avia-button color-ci-black hover-white avia-icon_select-no avia-size-medium\"><span>Naar de Duitse Stedenbouwprijs 2025<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.<\/p>\n","protected":false},"author":4,"featured_media":53797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[830,837,841,842],"tags":[909,1066,1755,1756,1757,1758],"class_list":["post-54158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dortmund-nl","category-stedelijke-planning","category-administratie","category-concurrentie","tag-erkenningsdag","tag-dortmund-nl","tag-stedelijke-ontwikkeling","tag-stedenbouwprijs","tag-haven","tag-lensing-media-port-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erkenning bij de Duitse Stedenbouwprijs | SHA<\/title>\n<meta name=\"description\" content=\"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erkenning bij de Duitse Stedenbouwprijs | SHA\" \/>\n<meta property=\"og:description\" content=\"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\" \/>\n<meta property=\"og:site_name\" content=\"SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-05T06:51:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T13:56:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-1030x773.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Max Frittgen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Max Frittgen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\"},\"author\":{\"name\":\"Max Frittgen\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl#\\\/schema\\\/person\\\/e5274be999acaa73cf6ce0a26902e296\"},\"headline\":\"Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe\",\"datePublished\":\"2025-08-05T06:51:21+00:00\",\"dateModified\":\"2025-08-12T13:56:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\"},\"wordCount\":964,\"image\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/DJI_20250509141849_0098-scaled-e1754373154559.jpg\",\"keywords\":[\"Erkenningsdag\",\"Dortmund\",\"Stedelijke ontwikkeling\",\"Stedenbouwprijs\",\"Haven\",\"Lensing Media Port\"],\"articleSection\":[\"Dortmund\",\"Stedelijke planning\",\"Administratie\",\"Concurrentie\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\",\"url\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\",\"name\":\"Erkenning bij de Duitse Stedenbouwprijs | SHA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/DJI_20250509141849_0098-scaled-e1754373154559.jpg\",\"datePublished\":\"2025-08-05T06:51:21+00:00\",\"dateModified\":\"2025-08-12T13:56:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl#\\\/schema\\\/person\\\/e5274be999acaa73cf6ce0a26902e296\"},\"description\":\"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage\",\"url\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/DJI_20250509141849_0098-scaled-e1754373154559.jpg\",\"contentUrl\":\"https:\\\/\\\/sha.de\\\/wp-content\\\/uploads\\\/DJI_20250509141849_0098-scaled-e1754373154559.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"default\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl\\\/news\\\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sha.de\\\/nl\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl#website\",\"url\":\"https:\\\/\\\/sha.de\\\/nl\",\"name\":\"SHA Scheffler Helbich Architekten GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sha.de\\\/nl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sha.de\\\/nl#\\\/schema\\\/person\\\/e5274be999acaa73cf6ce0a26902e296\",\"name\":\"Max Frittgen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g\",\"caption\":\"Max Frittgen\"},\"sameAs\":[\"http:\\\/\\\/www.sha.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erkenning bij de Duitse Stedenbouwprijs | SHA","description":"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse","og_locale":"nl_NL","og_type":"article","og_title":"Erkenning bij de Duitse Stedenbouwprijs | SHA","og_description":"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.","og_url":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse","og_site_name":"SHA Scheffler Helbich Architekten GmbH","article_published_time":"2025-08-05T06:51:21+00:00","article_modified_time":"2025-08-12T13:56:58+00:00","og_image":[{"width":1030,"height":773,"url":"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-1030x773.jpg","type":"image\/jpeg"}],"author":"Max Frittgen","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Max Frittgen","Geschatte leestijd":"6 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#article","isPartOf":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse"},"author":{"name":"Max Frittgen","@id":"https:\/\/sha.de\/nl#\/schema\/person\/e5274be999acaa73cf6ce0a26902e296"},"headline":"Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe","datePublished":"2025-08-05T06:51:21+00:00","dateModified":"2025-08-12T13:56:58+00:00","mainEntityOfPage":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse"},"wordCount":964,"image":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage"},"thumbnailUrl":"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-scaled-e1754373154559.jpg","keywords":["Erkenningsdag","Dortmund","Stedelijke ontwikkeling","Stedenbouwprijs","Haven","Lensing Media Port"],"articleSection":["Dortmund","Stedelijke planning","Administratie","Concurrentie"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse","url":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse","name":"Erkenning bij de Duitse Stedenbouwprijs | SHA","isPartOf":{"@id":"https:\/\/sha.de\/nl#website"},"primaryImageOfPage":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage"},"image":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage"},"thumbnailUrl":"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-scaled-e1754373154559.jpg","datePublished":"2025-08-05T06:51:21+00:00","dateModified":"2025-08-12T13:56:58+00:00","author":{"@id":"https:\/\/sha.de\/nl#\/schema\/person\/e5274be999acaa73cf6ce0a26902e296"},"description":"Het havengebied S\u00fcdliche Speicherstra\u00dfe in Dortmund is onderscheiden met een erkenning bij de Duitse Stedenbouwprijs 2025.","breadcrumb":{"@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#primaryimage","url":"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-scaled-e1754373154559.jpg","contentUrl":"https:\/\/sha.de\/wp-content\/uploads\/DJI_20250509141849_0098-scaled-e1754373154559.jpg","width":2560,"height":1920,"caption":"default"},{"@type":"BreadcrumbList","@id":"https:\/\/sha.de\/nl\/news\/erkenning-voor-het-havengebied-suedliche-speicherstrasse#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sha.de\/nl"},{"@type":"ListItem","position":2,"name":"Erkenning voor het havengebied S\u00fcdliche Speicherstra\u00dfe"}]},{"@type":"WebSite","@id":"https:\/\/sha.de\/nl#website","url":"https:\/\/sha.de\/nl","name":"SHA Scheffler Helbich Architekten GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sha.de\/nl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/sha.de\/nl#\/schema\/person\/e5274be999acaa73cf6ce0a26902e296","name":"Max Frittgen","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2412b8cfc9e1dc689e55df7d19e72589baa82cf33ed35837abe3925140890a8a?s=96&d=mm&r=g","caption":"Max Frittgen"},"sameAs":["http:\/\/www.sha.de"]}]}},"_links":{"self":[{"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/posts\/54158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/comments?post=54158"}],"version-history":[{"count":3,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/posts\/54158\/revisions"}],"predecessor-version":[{"id":54161,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/posts\/54158\/revisions\/54161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/media\/53797"}],"wp:attachment":[{"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/media?parent=54158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/categories?post=54158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sha.de\/nl\/wp-json\/wp\/v2\/tags?post=54158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}