{"id":38725,"date":"2019-12-06T11:46:32","date_gmt":"2019-12-06T10:46:32","guid":{"rendered":"https:\/\/sha.de\/o-nosso-escritorio\/filosofia"},"modified":"2024-08-28T15:02:03","modified_gmt":"2024-08-28T13:02:03","slug":"filosofia","status":"publish","type":"page","link":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia","title":{"rendered":"Filosofia"},"content":{"rendered":"<div id='av_section_1' class='avia-section main_color pt-default pb-default avia-no-border-styling avia-bg-style-scroll  avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap fullsize' style=' '  ><div class='container' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-38725'><div class='entry-content-wrapper clearfix'>\n\n\t\t\t<div id=\"av-k35rc5fq\" class=\"headline-column flex_column av_one_full flex_column_div first \">\n\t\t\t\t<div class=\"headline-wrap is-outside align-left sub-bottom\">\n\t\t\t\t\t<h1 class=\"headline-content headline-primary\">A nossa filosofia, a nossa autoimagem<\/h1>\n\t\t\t\t\t<h3 class=\"headline-content headline-secondary\">Como pensa e trabalha a SHA<\/h3>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding first bg-grey  split img-right   avia-builder-el-2  el_after_pixel_sc_headline  el_before_av_one_third  w-1023-full \"><div class=\"flex_column_inner split-content\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Conce\u00e7\u00e3o<\/h2>\n<p>Moldamos o nosso ambiente e queremos torn\u00e1-lo melhor e mais habit\u00e1vel com os nossos edif\u00edcios e instala\u00e7\u00f5es. Se o conseguirmos fazer, seremos bem sucedidos. A arquitetura e o planeamento urbano formam o espa\u00e7o p\u00fablico e os ambientes de trabalho e de vida. Ao contr\u00e1rio da arte, \u00e9 imposs\u00edvel escapar \u00e0 arquitetura e ao urbanismo porque estamos sempre a mover-nos dentro deles. E, ao contr\u00e1rio da moda, a arquitetura deve ser duradoura, intemporal e coerente, porque n\u00e3o podemos simplesmente descart\u00e1-la ou substitu\u00ed-la.<\/p>\n<p>Isto significa que temos uma responsabilidade especial n\u00e3o s\u00f3 para com o nosso cliente, mas tamb\u00e9m para com o p\u00fablico em geral.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column_inner split-image\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/stadt-turm-quadrat.jpg); background-position: center right; background-repeat: no-repeat; background-size: cover; \"><\/div><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-4  el_after_av_two_third  el_before_av_one_third  w-1023-full w-1023-ctm \"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>&#8220;Cuidador&#8221;<\/h2>\n<p>Somos curiosos, ouvimos com muita aten\u00e7\u00e3o e analisamos com precis\u00e3o requisitos complexos. N\u00e3o encaramos as tarefas de constru\u00e7\u00e3o com condi\u00e7\u00f5es de enquadramento dif\u00edceis como uma restri\u00e7\u00e3o, mas sim como um desafio especial no qual podemos demonstrar a nossa compet\u00eancia. Ao longo de todo o processo, consideramo-nos como um cuidador pragm\u00e1tico e orientado para a solu\u00e7\u00e3o, que mant\u00e9m todos os fios juntos com uma vis\u00e3o geral e prospetiva. Fazemos avan\u00e7ar o planeamento com continuidade, fiabilidade e precis\u00e3o &#8211; at\u00e9 \u00e0 realiza\u00e7\u00e3o detalhada. Estamos \u00e0 disposi\u00e7\u00e3o do cliente como parceiro de contacto para quaisquer quest\u00f5es.<\/p>\n<p>Isto permite que a empresa continue a concentrar-se na sua atividade principal. A nossa gest\u00e3o de constru\u00e7\u00e3o acompanha a execu\u00e7\u00e3o no local em toda a Alemanha e \u00e9 um conselheiro fi\u00e1vel e um solucionador de problemas durante a fase de constru\u00e7\u00e3o e depois dela.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default  fill img-right   avia-builder-el-6  el_after_av_one_third  el_before_av_one_third  w-1023-half column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/Zukunftsvision-Langfristigkeit-706x564.jpg); background-position: center left; background-repeat: no-repeat; background-size: cover; \"><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-7  el_after_av_one_third  el_before_av_one_third  w-1023-half column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Car\u00e1cter duradouro<\/h2>\n<p>As estrat\u00e9gias empresariais a longo prazo exigem um planeamento orientado para o futuro. Uma empresa de sucesso n\u00e3o v\u00ea apenas o aqui e o agora, mas deve tamb\u00e9m planear o futuro para utilizar eficazmente as oportunidades e o potencial de desenvolvimento. \u00c9 isso que a SHA faz.<\/p>\n<p>Pensamos sempre fora da caixa para os nossos clientes e vemos cada tarefa como um bloco de constru\u00e7\u00e3o num contexto mais vasto. Qual \u00e9 a procura a curto, m\u00e9dio e longo prazo? Como podem ser criadas sinergias? Como \u00e9 que os sistemas existentes podem ser optimizados e integrados?<\/p>\n<p>Tudo isto s\u00e3o quest\u00f5es que talvez ultrapassem a tarefa cl\u00e1ssica da constru\u00e7\u00e3o, mas que tomamos por garantidas.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-grey   img-right   avia-builder-el-9  el_after_av_one_third  el_before_av_one_third  w-1023-full column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Efici\u00eancia econ\u00f3mica<\/h2>\n<p>Para n\u00f3s, a gest\u00e3o da constru\u00e7\u00e3o come\u00e7a na fase de conce\u00e7\u00e3o. Muito antes da chegada da primeira escavadora, a nossa equipa de gest\u00e3o da constru\u00e7\u00e3o trabalha com os projectistas para garantir o cumprimento dos custos e dos prazos. Os calend\u00e1rios iniciais s\u00e3o elaborados no in\u00edcio do projeto, sendo depois aperfei\u00e7oados e optimizados \u00e0 medida que o projeto avan\u00e7a. O nosso controlo de projectos oferece aos nossos clientes um controlo transparente dos custos: desde o enquadramento dos custos no in\u00edcio do planeamento at\u00e9 \u00e0 determina\u00e7\u00e3o dos custos na conclus\u00e3o do projeto. O cumprimento do or\u00e7amento acordado em conjunto e das normas acordadas \u00e9 sempre a nossa principal prioridade. \u00c9 por isso que apostamos no contacto pessoal e na nossa presen\u00e7a no local da obra.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-grey   img-right   avia-builder-el-11  el_after_av_one_third  el_before_av_two_third  w-1023-full w-1023-reset column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-04ec88eef00220fa32cfda19f65cab19 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Individualidade<\/h2>\n<p>Cada projeto de constru\u00e7\u00e3o \u00e9 individual e requer uma solu\u00e7\u00e3o personalizada. Por esta raz\u00e3o, um projeto come\u00e7a para n\u00f3s ainda antes do planeamento propriamente dito, com a fase zero do servi\u00e7o, na qual nos preocupamos sobretudo em compreender o nosso cliente, as suas necessidades e os processos organizacionais e funcionais.<\/p>\n<p>Isto estabelece a base para um planeamento hol\u00edstico e um projeto inovador e bem sucedido. \u00c9 assim que damos identidade e car\u00e1cter aos nossos edif\u00edcios.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding  bg-default  fill img-right   avia-builder-el-13  el_after_av_one_third  el_before_av_one_third  w-1023-full column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/skizze-langer-schnitt-b1.jpg); background-position: center left; background-repeat: no-repeat; background-size: cover; \"><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default border-bottom   img-right   avia-builder-el-14  el_after_av_two_third  el_before_av_two_third  w-1023-full invalid-custom-class-found column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Funcionalidade<\/h2>\n<p>A origem da palavra &#8220;arquitetura&#8221; significa &#8220;arte de construir&#8221;. Para a SHA, traduzimos isto numa atitude: quando a arquitetura pragm\u00e1tica emerge dos requisitos log\u00edsticos e funcionais dos nossos clientes, podemos criar um verdadeiro valor acrescentado &#8211; e uma arquitetura tal como a entendemos. Fiel ao lema <span class=\"ILfuVd\"><span class=\"e24Kjd\"> &#8220;a forma segue a fun\u00e7\u00e3o&#8221;, como Mies van der Rohe j\u00e1 sabia. <\/span><\/span> <\/p>\n<p>Apresentamos-lhe solu\u00e7\u00f5es criativas em que a est\u00e9tica, a funcionalidade e a rentabilidade andam de m\u00e3os dadas.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding  bg-grey  split img-right   avia-builder-el-16  el_after_av_one_third  el_before_av_one_third  w-1023-full invalid-custom-class-found column-top-margin\"><div class=\"flex_column_inner split-content\"><section  class='av_textblock_section av-k35rkyu0-04ec88eef00220fa32cfda19f65cab19 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Comunica\u00e7\u00e3o<\/h2>\n<p>Uma troca respeitosa em p\u00e9 de igualdade &#8211; isto n\u00e3o \u00e9 apenas importante para n\u00f3s no escrit\u00f3rio, mas tamb\u00e9m nas nossas rela\u00e7\u00f5es quotidianas com os nossos clientes e parceiros.  <\/p>\n<p>Acompanhamos e apoiamos os nossos clientes em todas as fases do projeto. Um n\u00edvel pessoal com pessoas de contacto fixas e uma coopera\u00e7\u00e3o de confian\u00e7a s\u00e3o para n\u00f3s o essencial. A melhor confirma\u00e7\u00e3o do nosso trabalho \u00e9 quando somos novamente contratados e podemos realizar projectos de acompanhamento com os nossos clientes.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column_inner split-image\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/Kommunikation-Stoschek-706x564.jpg); background-position: center right; background-repeat: no-repeat; background-size: cover; \"><\/div><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default   img-right   avia-builder-el-18  el_after_av_two_third  el_before_av_one_third  w-1023-full column-top-margin\"><div class=\"call-to-action   has-button ci-black hover-white bg-yellow  align-left \"><div class=\"call-to-action__inner\"><div class=\"call-to-action__text\"><span class=\"call-to-action__primary\">O nosso  <br \/>Servi\u00e7os.<\/span><span class=\"call-to-action__secondary\">Est\u00e1 em boas m\u00e3os com a SHA.<\/span><\/div><div class=\"call-to-action__button\"><div class=\"avia-button-wrap theme-fill avia-button-left\"><a href=\"https:\/\/sha.de\/leistungen\/beratung\" class=\"avia-button color-ci-black hover-white avia-icon_select-no avia-size-medium\"><span>O que podemos fazer por si<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-20  el_after_av_one_third  el_before_av_one_third  w-1023-half w-1023-ml-off column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Sustentabilidade<\/h2>\n<p>Aos nossos olhos, a boa arquitetura nasce quando se consegue criar valor acrescentado a partir da s\u00edntese de todas as qualidades funcionais, ecol\u00f3gicas, estruturais-espaciais, econ\u00f3micas e, sobretudo, socioculturais, raramente mencionadas no programa de exig\u00eancias de um projeto, de que todos beneficiam a longo prazo &#8211; e, portanto, de forma sustent\u00e1vel. O nosso objetivo nos projectos de constru\u00e7\u00e3o \u00e9 desenvolver conceitos claros e facilmente compreens\u00edveis, utilizando recursos cuidadosamente utilizados.<\/p>\n<p>A SHA j\u00e1 est\u00e1 a implementar muitas medidas de poupan\u00e7a de recursos, n\u00e3o s\u00f3 no local de constru\u00e7\u00e3o, mas tamb\u00e9m no escrit\u00f3rio.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default  fill img-right   avia-builder-el-22  el_after_av_one_third  avia-builder-el-last  w-1023-half column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/philosophie_nachhaltigkeit.jpg); background-position: center center; background-repeat: no-repeat; background-size: cover; \"><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2' class='avia-section main_color pt-large pb-default avia-no-border-styling avia-bg-style-scroll  avia-builder-el-23  el_after_av_section  avia-builder-el-last   container_wrap fullsize' style=' '  ><div class='container' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-38725'><div class='entry-content-wrapper clearfix'>\n\n\t\t\t<div id=\"av-k35rc5fq\" class=\"headline-column flex_column av_one_full flex_column_div first \">\n\t\t\t\t<div class=\"headline-wrap is-outside align-left sub-bottom\">\n\t\t\t\t\t<h2 class=\"headline-content headline-primary\">Os nossos valores<\/h2>\n\t\t\t\t\t<h3 class=\"headline-content headline-secondary\">Isto \u00e9 o que vivemos (antes)<\/h3>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding first bg-grey  split img-right   avia-builder-el-25  el_after_pixel_sc_headline  el_before_av_one_third  w-1023-full invalid-custom-class-found \"><div class=\"flex_column_inner split-content\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Juntos<\/h2>\n<p>O nosso trabalho baseia-se numa rela\u00e7\u00e3o aberta e leal entre n\u00f3s, na honestidade e na compet\u00eancia profissional. Cada colaborador \u00e9 valorizado pela sua singularidade e pelas suas compet\u00eancias especiais. Com esta base, a SHA est\u00e1 agora na sua quarta gera\u00e7\u00e3o de sucesso e j\u00e1 realizou in\u00fameros projectos de constru\u00e7\u00e3o. Os erros tamb\u00e9m acontecem &#8211; e discutimo-los de forma construtiva para aprendermos com eles. O feedback regular e as entrevistas de avalia\u00e7\u00e3o ajudam cada indiv\u00edduo e a empresa a progredir.<\/p>\n<p>Temos hierarquias planas, responsabilidades claras e somos consistentes nos nossos processos de trabalho.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column_inner split-image\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/Miteinander3-706x564.jpg); background-position: top left; background-repeat: no-repeat; background-size: cover; \"><\/div><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-27  el_after_av_two_third  el_before_av_one_third  w-1023-full w-1023-ctm \"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Forma\u00e7\u00e3o cont\u00ednua<\/h2>\n<p>O mundo est\u00e1 a mudar rapidamente. Por isso, \u00e9 ainda mais importante manter-se atualizado. A transfer\u00eancia interna de conhecimentos \u00e9 muito importante para n\u00f3s. N\u00e3o damos palestras, mas entramos em di\u00e1logo uns com os outros. O nosso objetivo \u00e9 garantir que os nossos programas t\u00e9cnicos e os nossos colaboradores estejam sempre na vanguarda. Investimos na forma\u00e7\u00e3o cont\u00ednua e promovemos a participa\u00e7\u00e3o em semin\u00e1rios especializados, cursos de forma\u00e7\u00e3o e programas de estudo a tempo parcial. Desta forma, beneficiamos da experi\u00eancia e dos impulsos dos outros, ou seja, do proverbial pensar fora da caixa: para que possamos oferecer-lhe solu\u00e7\u00f5es \u00f3ptimas e contempor\u00e2neas em todas as fases do servi\u00e7o e para que possamos antecipar e pensar em poss\u00edveis desafios.<\/p>\n<p>E tamb\u00e9m partilhamos os nossos conhecimentos: A miss\u00e3o de ensino e uma c\u00e1tedra convidada de gest\u00e3o de SHA na Universidade de Ci\u00eancias Aplicadas e Artes de Dortmund, bem como numerosas palestras em toda a Alemanha, s\u00e3o exemplos disso.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default  fill img-right   avia-builder-el-29  el_after_av_one_third  el_before_av_one_third  w-1023-half column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/Familie-706x564.jpg); background-position: center left; background-repeat: no-repeat; background-size: cover; \"><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-30  el_after_av_one_third  el_before_av_one_third  w-1023-half column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Fam\u00edlia<\/h2>\n<p>N\u00e3o somos apenas uma empresa familiar, tamb\u00e9m vivemos esta atitude &#8211; e apoiamos os nossos colaboradores em todas as situa\u00e7\u00f5es. Afinal, uma empresa \u00e9 t\u00e3o boa quanto os seus empregados, que dominam as pequenas e grandes tarefas quotidianas todos os dias.<\/p>\n<p>Criamos um ambiente em que, por exemplo, as circunst\u00e2ncias da vida individual s\u00e3o tidas em conta com diferentes modelos de hor\u00e1rio de trabalho.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-grey   img-right   avia-builder-el-32  el_after_av_one_third  el_before_av_one_third  w-1023-full invalid-custom-class-found column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>In\u00edcio<\/h2>\n<p>Adoramos a regi\u00e3o do Ruhr. Como empresa familiar de quarta gera\u00e7\u00e3o sediada em Dortmund, sentimo-nos particularmente comprometidos com o local. Em termos concretos, isto significa que a partir daqui, uma das maiores aglomera\u00e7\u00f5es urbanas da Europa, planeamos edif\u00edcios em toda a Alemanha. Os nossos clientes valorizam a nossa especializa\u00e7\u00e3o.<\/p>\n<p>E se n\u00e3o estivermos no seu local de constru\u00e7\u00e3o, mas voc\u00ea estiver no local connosco, teremos todo o gosto em mostrar-lhe o encanto da Potts.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-grey   img-right   avia-builder-el-34  el_after_av_one_third  el_before_av_two_third  w-1023-full w-1023-reset column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-d38ffd973b55be26393d8664b65735ee '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Compromisso<\/h2>\n<p>Pensamos fora da caixa e cumprimos a nossa responsabilidade social. A SHA est\u00e1 envolvida localmente: A <a href=\"https:\/\/gast-haus.org\/\" target=\"_blank\" rel=\"noopener nofollow\">Gast-Haus<\/a>, uma iniciativa ecum\u00e9nica para os sem-abrigo no centro da cidade de Dortmund, tem sido apoiada pelo nosso gabinete de arquitetura h\u00e1 muitos anos com v\u00e1rios projectos de constru\u00e7\u00e3o e donativos. Estamos convencidos de que o trabalho da Casa de H\u00f3spedes pode ajudar as pessoas necessitadas e aliviar o seu sofrimento. Tamb\u00e9m apoiamos o clube local de andebol OSC na sua caminhada para a liga. O que \u00e9 que tem de especial: N\u00e3o s\u00f3 somos um patrocinador e parceiro orgulhoso, como tamb\u00e9m sabemos que o t\u00e9cnico da OSC \u00e9 um gestor de constru\u00e7\u00e3o fi\u00e1vel no nosso c\u00edrculo de colegas. Para n\u00f3s, ambos s\u00e3o um grande sucesso.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding  bg-default  fill img-right   avia-builder-el-36  el_after_av_one_third  el_before_av_one_third  w-1023-full invalid-custom-class-found column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/PHOENIXWERK_Spatenstich_SHA_F\u00fcllfoto-706x564.jpg); background-position: center left; background-repeat: no-repeat; background-size: cover; \"><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first bg-default   img-left   avia-builder-el-37  el_after_av_two_third  el_before_av_one_third  w-1023-full invalid-custom-class-found column-top-margin\"><div class=\"call-to-action   has-button ci-black hover-white bg-yellow  align-left \"><div class=\"call-to-action__inner\"><div class=\"call-to-action__text\"><span class=\"call-to-action__primary\">Jogador de equipa  <br \/>desejado.<\/span><span class=\"call-to-action__secondary\">Gostaria de participar?  <br \/>Fa\u00e7a parte da SHA!<\/span><\/div><div class=\"call-to-action__button\"><div class=\"avia-button-wrap theme-fill avia-button-left\"><a href=\"https:\/\/sha.de\/karriere\/stellenangebote\" class=\"avia-button color-ci-black hover-white avia-icon_select-no avia-size-medium\"><span>Saiba mais<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default border-bottom   img-right   avia-builder-el-39  el_after_av_one_third  el_before_av_one_third  w-1023-half w-1023-ml-off column-top-margin\"><section  class='av_textblock_section av-k35rkyu0-04ec88eef00220fa32cfda19f65cab19 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Sa\u00fade<\/h2>\n<p>&#8220;Uma mente saud\u00e1vel vive num corpo saud\u00e1vel&#8221;. A sa\u00fade dos nossos colaboradores \u00e9 muito importante para n\u00f3s. Com o nosso pr\u00f3prio grupo desportivo da empresa, que se re\u00fane semanalmente para correr, treinar a coordena\u00e7\u00e3o e a forma f\u00edsica, postos de trabalho flex\u00edveis e equipamento inform\u00e1tico ergon\u00f3mico, fazemos muito para promover um local de trabalho saud\u00e1vel. Tamb\u00e9m permitimos a participa\u00e7\u00e3o nas corridas de empresa de Dortmund e oferecemos o aluguer de uma bicicleta el\u00e9ctrica para o trajeto para o trabalho.  <\/p>\n<p>E no escrit\u00f3rio h\u00e1 fruta fresca, \u00e1gua e caf\u00e9 para tomar uma e outra vez.<\/p>\n<\/div><\/section><\/div><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding  bg-default  fill img-right   avia-builder-el-41  el_after_av_one_third  avia-builder-el-last  w-1023-half column-top-margin\" style=\"background-image: url(https:\/\/sha.de\/wp-content\/uploads\/Firmenlauf_2019-4.jpg); background-position: center center; background-repeat: no-repeat; background-size: cover; \"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":30205,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-38725","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filosofia | SHA Scheffler Helbich Architekten GmbH<\/title>\n<meta name=\"description\" content=\"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filosofia | SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"og:description\" content=\"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia\" \/>\n<meta property=\"og:site_name\" content=\"SHA Scheffler Helbich Architekten GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T13:02:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\\\/filosofia\",\"url\":\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\\\/filosofia\",\"name\":\"Filosofia | SHA Scheffler Helbich Architekten GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sha.de\\\/pt-pt#website\"},\"datePublished\":\"2019-12-06T10:46:32+00:00\",\"dateModified\":\"2024-08-28T13:02:03+00:00\",\"description\":\"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\\\/filosofia#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\\\/filosofia\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\\\/filosofia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sha.de\\\/pt-pt\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O nosso escrit\u00f3rio\",\"item\":\"https:\\\/\\\/sha.de\\\/pt-pt\\\/o-nosso-escritorio\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filosofia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sha.de\\\/pt-pt#website\",\"url\":\"https:\\\/\\\/sha.de\\\/pt-pt\",\"name\":\"SHA Scheffler Helbich Architekten GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sha.de\\\/pt-pt?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filosofia | SHA Scheffler Helbich Architekten GmbH","description":"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia","og_locale":"pt_PT","og_type":"article","og_title":"Filosofia | SHA Scheffler Helbich Architekten GmbH","og_description":"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.","og_url":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia","og_site_name":"SHA Scheffler Helbich Architekten GmbH","article_modified_time":"2024-08-28T13:02:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"27 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia","url":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia","name":"Filosofia | SHA Scheffler Helbich Architekten GmbH","isPartOf":{"@id":"https:\/\/sha.de\/pt-pt#website"},"datePublished":"2019-12-06T10:46:32+00:00","dateModified":"2024-08-28T13:02:03+00:00","description":"A nossa filosofia, a nossa autoimagem: \u00e9 assim que o gabinete de arquitetura SHA, com escrit\u00f3rios em Dortmund e Berlim, pensa e trabalha.","breadcrumb":{"@id":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio\/filosofia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sha.de\/pt-pt"},{"@type":"ListItem","position":2,"name":"O nosso escrit\u00f3rio","item":"https:\/\/sha.de\/pt-pt\/o-nosso-escritorio"},{"@type":"ListItem","position":3,"name":"Filosofia"}]},{"@type":"WebSite","@id":"https:\/\/sha.de\/pt-pt#website","url":"https:\/\/sha.de\/pt-pt","name":"SHA Scheffler Helbich Architekten GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sha.de\/pt-pt?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/pages\/38725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/comments?post=38725"}],"version-history":[{"count":1,"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/pages\/38725\/revisions"}],"predecessor-version":[{"id":38731,"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/pages\/38725\/revisions\/38731"}],"up":[{"embeddable":true,"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/pages\/30205"}],"wp:attachment":[{"href":"https:\/\/sha.de\/pt-pt\/wp-json\/wp\/v2\/media?parent=38725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}